{"id":119,"date":"2016-07-28T13:30:36","date_gmt":"2016-07-28T11:30:36","guid":{"rendered":"https:\/\/www.die-oswalds.de\/blog\/?p=119"},"modified":"2019-03-17T08:52:11","modified_gmt":"2019-03-17T07:52:11","slug":"mittlere-maustaste-als-doppelklick","status":"publish","type":"post","link":"https:\/\/www.die-oswalds.de\/blog\/2016\/07\/28\/mittlere-maustaste-als-doppelklick\/","title":{"rendered":"Mittlere Maustaste als Doppelklick"},"content":{"rendered":"<p>Aktuelle M\u00e4use kommen mit vielen Tasten, sogar die g\u00fcnstigsten haben heutzutage meistens drei, wobei die dritte oft unter dem Rad versteckt ist. Das Rad ist also nicht nur zum scrollen da. Allerdings wird von Windows aus die mittlere Taste als Panning-Funktion hinterlegt. Das hei\u00dft, wenn man diese bet\u00e4tigt, erscheint meistens ein Kreis und man kann sich mit der Maus durch das Dokument oder die Webseite &#8222;schieben&#8220;. Eine Funktion, \u00fcber die sich streiten l\u00e4sst. Einige Hersteller bieten in ihren Treibern die M\u00f6glichkeit, die Tastenbelegung zu \u00e4ndern, zum Beispiel in einen Doppelklick, was wohl in meiner Ansicht n\u00fctzlicher ist als diese Panning-Funktion.<\/p>\n<p>Was aber wenn, es keinen Treiber vom Hersteller gibt oder dieser einfach die Doppelklick-Funktion nicht mehr unterst\u00fctzt? Vielleicht m\u00f6chte man auch einfach nicht den 80 MB gro\u00dfen Treiber installieren? Die L\u00f6sung daf\u00fcr ist ein\u00a0 kleines Programm (und wenn ich klein sage meine ich 3KB) aus dem Jahr 2006 von Dean Harding, das von Andrew Robinson in MASM32 \u00fcbersetzt wurde.<\/p>\n<p><a href=\"http:\/\/www.codeka.com.au\/blog\/2006\/09\/new_version_of_dblclk\" target=\"_blank\" rel=\"noopener\">http:\/\/www.codeka.com.au\/blog\/2006\/09\/new_version_of_dblclk<\/a><\/p>\n<p>Leider ist der Download-Link im obigen Artikel tot. Darum gibt es diesen auch hier, inklusive den MASM32 Source Code.<\/p>\n<p><a href=\"http:\/\/www.die-oswalds.de\/downloads\/DblClick.zip\">Download<\/a><\/p>\n<p>Zur Installation: Einfach die EXE-Datei auspacken und in den Autostart-Ordner kopieren. Jetzt startet das &#8222;DoubleKlick&#8220;-Programm jedes Mal, wenn der Computer hoch f\u00e4hrt. Und zum Deinstallieren einfach die Datei aus dem Autostart-Ordner l\u00f6schen und den Computer neu starten.<\/p>\n<p>Getestet habe ich dieses Programm mit Windows 7 und 10.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aktuelle M\u00e4use kommen mit vielen Tasten, sogar die g\u00fcnstigsten haben heutzutage meistens drei, wobei die dritte oft unter dem Rad versteckt ist. Das Rad ist also nicht nur zum scrollen da. Allerdings wird von Windows aus die mittlere Taste als Panning-Funktion hinterlegt. Das hei\u00dft, wenn man diese bet\u00e4tigt, erscheint meistens ein Kreis und man kann [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[15,13,14],"class_list":["post-119","post","type-post","status-publish","format-standard","hentry","category-windows","tag-doppelklick","tag-maus","tag-windows","clear"],"_links":{"self":[{"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/posts\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":0,"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/posts\/119\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/media?parent=119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/categories?post=119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-oswalds.de\/blog\/wp-json\/wp\/v2\/tags?post=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}